{"id":1310,"date":"2017-12-14T01:18:31","date_gmt":"2017-12-14T01:18:31","guid":{"rendered":"https:\/\/www.losangelesemploymentattorney.org\/?page_id=1310"},"modified":"2025-12-11T22:18:44","modified_gmt":"2025-12-11T22:18:44","slug":"abogado-de-acoso-en-ambiente-laboral-hostil-2","status":"publish","type":"page","link":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/","title":{"rendered":"Abogado demandar\u00e1 al empleador por ambiente laboral hostil"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1313 aligncenter\" src=\"https:\/\/www.losangelesemploymentattorney.org\/wp-content\/uploads\/2017\/12\/hostile-work-env.jpg\" alt=\"Abogado demandar\u00e1 al empleador por ambiente laboral hostil\" width=\"800\" height=\"512\" srcset=\"https:\/\/www.losangelesemploymentattorney.org\/wp-content\/uploads\/2017\/12\/hostile-work-env.jpg 800w, https:\/\/www.losangelesemploymentattorney.org\/wp-content\/uploads\/2017\/12\/hostile-work-env-600x384.jpg 600w, https:\/\/www.losangelesemploymentattorney.org\/wp-content\/uploads\/2017\/12\/hostile-work-env-300x192.jpg 300w, https:\/\/www.losangelesemploymentattorney.org\/wp-content\/uploads\/2017\/12\/hostile-work-env-768x492.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Todo empleado tiene derecho a un lugar de trabajo seguro y acogedor. Se han implementado muchas leyes para garantizar que se mantenga la paz en el entorno laboral, tanto interna como externamente. Tambi\u00e9n se han aprobado leyes que impiden <a href=\"https:\/\/www.losangelesemploymentattorney.org\/es\/areas-de-practica-2\/acoso-por-hostilidad-en-el-lugar-de-trabajo-2\/\">discriminaci\u00f3n en el trabajo<\/a> \u2013 esto significa que, como posible empleado, no se le puede discriminar durante el proceso de contrataci\u00f3n y, al recibir el trabajo, no se le puede discriminar mientras trabaja. El acoso en el lugar de trabajo est\u00e1 penado por la ley y usted puede ganar un acuerdo considerable si su caso lo maneja adecuadamente el abogado adecuado. Nuestro bufete de abogados en Bakersfield cuenta con un equipo de abogados expertos que pueden ayudarlo a ganar su demanda por ambiente laboral hostil. Nuestros clientes nos llaman con preguntas sobre este tipo de demandas y qu\u00e9 pasos pueden tomar, as\u00ed como si pueden presentar una demanda contra la empresa (la respuesta es s\u00ed, puede demandar a su empleador). Ejemplos de estas preguntas incluyen:<\/p>\n<ul>\n<li>\u00bfD\u00f3nde puedo encontrar un abogado especializado en entornos laborales hostiles en Bakersfield?<\/li>\n<li>\u00bfQui\u00e9nes son los mejores abogados de lugares de trabajo hostiles en Bakersfield?<\/li>\n<li>\u00bfPuedo demandar a mi empleador por crear un ambiente de trabajo hostil?<\/li>\n<li>\u00bfC\u00f3mo puedo presentar una demanda por acoso laboral?<\/li>\n<\/ul>\n<h2>\u00bfQu\u00e9 es el acoso laboral?<\/h2>\n<p><a href=\"https:\/\/www.losangelesemploymentattorney.org\/es\/areas-de-practica-2\/acoso-por-hostilidad-en-el-lugar-de-trabajo-2\/\">Acoso laboral<\/a> se ha definido como una violaci\u00f3n de una persona al atacar su car\u00e1cter, raza, color, religi\u00f3n, sexo, orientaci\u00f3n sexual, etnia, edad, discapacidad, genes y m\u00e1s. Es importante se\u00f1alar que el acoso es una conducta no deseada; Las bromas entre amigos pueden no calificar como acoso laboral, aunque otro compa\u00f1ero de trabajo puede sentirse ofendido (y por lo tanto poder presentar una demanda por ambiente laboral hostil, a pesar de no ser el objetivo del acoso). El resultado es un entorno laboral que un trabajador razonable encontrar\u00eda intimidante, hostil u ofensivo. Algunos ejemplos comunes de acoso laboral incluyen:<\/p>\n<ul>\n<li>Rid\u00edculo<\/li>\n<li>Insultos<\/li>\n<li>Im\u00e1genes, fotograf\u00edas, pinturas, dibujos u objetos ofensivos.<\/li>\n<li>Insultar<\/li>\n<li>Agresiones f\u00edsicas o amenazas.<\/li>\n<li>Intimidaci\u00f3n o miedo<\/li>\n<li>Chistes o comentarios ofensivos.<\/li>\n<li>T\u00e9rminos despectivos o insultos<\/li>\n<li>Interferencia intencional con el desempe\u00f1o laboral.<\/li>\n<\/ul>\n<p>Sin embargo, estos niveles de acoso tienen grados. Los actos insignificantes y los incidentes aislados no ser\u00edan suficientes para constituir acoso en el lugar de trabajo, y las molestias y disturbios menores no ser\u00edan tratados con tanta severidad. Un abogado de Bakersfield puede brindarle m\u00e1s informaci\u00f3n sobre c\u00f3mo diferenciar entre los dos.<\/p>\n<p>Com\u00fanmente, nuestra firma de abogados ve casos de un ambiente de trabajo abusivo o un ambiente de trabajo intimidante (y la intimidaci\u00f3n en este sentido se hace a prop\u00f3sito, no surge del miedo o la inexperiencia del trabajador). No dude en consultar con un abogado en Bakersfield si se siente v\u00edctima de acoso en el lugar de trabajo.<\/p>\n<h2>Informaci\u00f3n legal<\/h2>\n<p><strong><br \/>\n<\/strong>Muchos actos de hostilidad en el trabajo violan alg\u00fan acto. La ley de California sobre entornos laborales hostiles coincide en su mayor parte con las leyes federales de prevenci\u00f3n de la discriminaci\u00f3n aprobadas en el pasado. Estas leyes incluyen el T\u00edtulo VII de la Ley de Derechos Civiles de 1964, que proh\u00edbe la discriminaci\u00f3n contra los empleados por motivos de sexo, color, raza, religi\u00f3n y origen nacional; la Ley de Discriminaci\u00f3n por Edad de 1967, que protege a los solicitantes y empleados de la discriminaci\u00f3n si tienen m\u00e1s de 40 a\u00f1os; y la Ley de Estadounidenses con Discapacidades de 1990, que no permite la discriminaci\u00f3n contra quienes tienen necesidades especiales o discapacidades f\u00edsicas.<\/p>\n<p>La violaci\u00f3n de estos actos puede tener consecuencias nefastas para las partes involucradas. No s\u00f3lo los perpetradores pueden ser castigados severamente, sino tambi\u00e9n la empresa si eran conscientes de la hostilidad en el trabajo y no hicieron nada para detenerla.<\/p>\n<h2>Pasos a seguir para presentar una demanda<\/h2>\n<p><strong><br \/>\n<\/strong>Ante cualquier inicio de acoso laboral, debes asegurarte de documentarlo lo mejor que puedas. Es posible que pueda tomar videos del acoso a medida que ocurre o grabar los comentarios y declaraciones. Debes pedir a otros compa\u00f1eros de trabajo sus testimonios, ya sean verbales o escritos, para respaldar tus afirmaciones. Puede resultar muy dif\u00edcil conseguir aliados en estas situaciones, ya que muchas personas temen por su propia seguridad laboral; aun as\u00ed, debe hacer todo lo posible para reunir pruebas suficientes, o el caso ser\u00e1 simplemente una cuesti\u00f3n de la palabra de una persona contra la de otra, y no habr\u00e1 manera de demostrar que ninguna de las partes tiene raz\u00f3n o no.<\/p>\n<p>Despu\u00e9s de tener evidencia adecuada de la hostilidad, debe comunicarse con su jefe o gerente para obtener ayuda. Lo ideal es que tu jefe se ocupe de la situaci\u00f3n o la traslade al departamento de Recursos Humanos de la empresa; sin embargo, hay muchas ocasiones en las que no se realiza ninguna acci\u00f3n y el acoso contin\u00faa sin control. Es mejor dejar un rastro impreso en forma de mensajes de texto y correos electr\u00f3nicos para demostrar que intent\u00f3 pedir ayuda y que esa ayuda fue ignorada o denegada.<\/p>\n<p>Si todo lo dem\u00e1s falla, comun\u00edquese con un abogado de Bakersfield con experiencia en casos de entornos laborales hostiles. No debe verse obligado a enfrentar los problemas solo y por su cuenta, y un abogado experto puede brindarle la asistencia que necesita para demandar a su jefe.<\/p>\n<p>Los clientes a menudo nos preguntan si demandar al empleador es una opci\u00f3n. La respuesta corta es s\u00ed, podemos demandar a su empleador. Nuestros abogados lo ayudar\u00e1n a reunir todas sus pruebas y presentar el caso a las partes necesarias; Si todo lo dem\u00e1s falla, estamos dispuestos a acudir a los tribunales para lograr un acuerdo.<\/p>\n<h2>Compensaci\u00f3n por una demanda por entorno laboral hostil en California<\/h2>\n<p><strong><br \/>\n<\/strong>Nuestra firma de abogados se ocupa principalmente de los derechos de los empleados en Bakersfield y en todo California. Nos esforzamos por ofrecerle el acuerdo m\u00e1s justo posible en caso de una demanda. Una demanda por acoso laboral puede generarle varios tipos de compensaci\u00f3n, que incluyen:<\/p>\n<ul>\n<li><strong>Salarios perdidos<\/strong>, que se puede obtener tanto del pasado como del futuro. Es posible que pueda ganar un pago debido a indemnizaciones, despidos y m\u00e1s.<\/li>\n<li><strong>Honorarios legales<\/strong>, o honorarios que los bufetes de abogados cobran por la representaci\u00f3n.<\/li>\n<li><strong>Dolor y sufrimiento<\/strong>, o da\u00f1os no econ\u00f3micos resultantes del estr\u00e9s de la discriminaci\u00f3n o el acoso. Estos da\u00f1os pueden incluir dolor psicol\u00f3gico, cicatrices mentales, trauma emocional, trastorno de estr\u00e9s postraum\u00e1tico, miedo, ansiedad, depresi\u00f3n y m\u00e1s.<\/li>\n<li><strong>Da\u00f1os punitivos<\/strong>, que son \u00fanicos en las demandas por hostilidad en el lugar de trabajo. Si hay una violaci\u00f3n de los principios raciales o de discapacidad, es posible que pueda obtener una indemnizaci\u00f3n punitiva, pero no si hay discriminaci\u00f3n por motivos de edad. Un abogado con experiencia en casos de ambiente laboral hostil en el lugar de trabajo puede ayudarlo a saber qu\u00e9 casos son elegibles para da\u00f1os punitivos. Los da\u00f1os punitivos en s\u00ed mismos son simplemente pagos monetarios adicionales destinados a castigar al infractor y disuadirlo de volver a cometer el acto. Los tribunales suelen ser reacios a concederlos, ya que pueden considerarlos excesivos y s\u00f3lo un abogado experto podr\u00e1 conseguirlos para su caso.<\/li>\n<\/ul>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre lo que puede ganar, <a href=\"#case-form\">p\u00f3ngase en contacto con un abogado de acoso laboral en Bakersfield<\/a>.<\/p>\n<h2>Grupo de abogados laborales de California: aqu\u00ed para protegerlo<\/h2>\n<p>Nuestro bufete de abogados en Bakersfield est\u00e1 aqu\u00ed para proteger los derechos de los trabajadores en Bakersfield y en todo el estado de California. No creemos que ning\u00fan individuo deba ser el <a href=\"https:\/\/www.losangelesemploymentattorney.org\/es\/areas-de-practica-2\/acoso-por-hostilidad-en-el-lugar-de-trabajo-2\/\">v\u00edctima de acoso laboral<\/a> o verse obligado a trabajar en una atm\u00f3sfera hostil o no deseada. Es posible que muchas personas ni siquiera sientan que est\u00e1n contribuyendo a un lugar de trabajo negativo, y algunos empleadores sienten lo mismo. Nuestro objetivo principal es asegurarnos de que reciba la compensaci\u00f3n que merece por estar sujeto a un lugar de trabajo hostil, pero tambi\u00e9n nos esforzamos por cambiar la din\u00e1mica y trabajaremos para ayudar a que su trabajo mejore. Nuestros abogados son agresivos y se esforzar\u00e1n incansablemente para lograr un acuerdo con la agencia de seguros de su empresa. Usted merece la compensaci\u00f3n m\u00e1s justa seg\u00fan la ley.<\/p>\n<p><a href=\"tel:18884518915\">Ll\u00e1manos<\/a> hoy para programar una consulta legal gratuita con un abogado experto. Le animamos a hacer cualquier pregunta que desee sobre su caso y estaremos encantados de responderlas. Le daremos la informaci\u00f3n necesaria sobre el tipo de demanda que se presentar\u00e1 y le informaremos c\u00f3mo se desarrolla el proceso legal. Tambi\u00e9n le diremos qu\u00e9 tan s\u00f3lido creemos que es su caso; otras firmas de abogados y abogados pueden mentirle sobre el valor de su caso en un intento de contratarlo para ganar tanto dinero como puedan para ellos mismos. Nuestros abogados son emp\u00e1ticos y veraces, y si su caso requiere m\u00e1s pruebas o no se puede ganar, se lo informaremos.<\/p>\n<p>Adem\u00e1s, se le ofrece una garant\u00eda de tarifa cero cuando contrata nuestros servicios legales. Esto significa que no pagar\u00e1 gastos de bolsillo durante todo el proceso del litigio. Nuestro bufete de abogados cubre todos los costos del caso para usted y solo nos pagan si ganamos su caso, y el dinero proviene del acuerdo que ganamos para usted. Esto se hace para garantizar que sus ahorros nunca se vean afectados. Creemos que cualquier persona que solicite asistencia jur\u00eddica debe recibirla, independientemente de su capacidad econ\u00f3mica. Si perdemos su caso, usted no nos deber\u00e1 nada en absoluto y nosotros asumiremos todos los costos.<\/p>\n<p><a href=\"#case-form\">Alcanzar<\/a> hacia <a href=\"\/es\/\">Grupo de Abogados de Empleo en Derecho Laboral de California<\/a> hablar con un abogado experimentado para demandar a su empleador por un ambiente de trabajo hostil.<\/p>","protected":false},"excerpt":{"rendered":"<p>Todo empleado tiene derecho a un lugar de trabajo seguro y acogedor. Se han implementado muchas leyes para garantizar que se mantenga la paz en el entorno laboral, tanto interna como externamente. Tambi\u00e9n se han aprobado leyes que impiden que se produzca discriminaci\u00f3n en el trabajo; esto significa que, como posible empleado, no puedes...<\/p>","protected":false},"author":1,"featured_media":0,"parent":1430,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-1310","page","type-page","status-publish"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Every employee is entitled to a safe and accepting workplace. There have been many laws implemented to make sure that peace is kept at job environments, both internally and externally. There have also been laws passed that prevent discrimination from taking place at a job \u2013 this means that, as a prospective employee, you cannot\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"California Labor Law Employment Attorneys Group -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Attorney to Sue Employer for Hostile Work Environment - California Labor Law Employment Attorneys Group\" \/>\n\t\t<meta property=\"og:description\" content=\"Every employee is entitled to a safe and accepting workplace. There have been many laws implemented to make sure that peace is kept at job environments, both internally and externally. There have also been laws passed that prevent discrimination from taking place at a job \u2013 this means that, as a prospective employee, you cannot\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-12-14T01:18:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-11T22:18:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Attorney to Sue Employer for Hostile Work Environment - California Labor Law Employment Attorneys Group\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Every employee is entitled to a safe and accepting workplace. There have been many laws implemented to make sure that peace is kept at job environments, both internally and externally. There have also been laws passed that prevent discrimination from taking place at a job \u2013 this means that, as a prospective employee, you cannot\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/#listItem\",\"name\":\"Practice Areas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/#listItem\",\"position\":2,\"name\":\"Practice Areas\",\"item\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/#listItem\",\"name\":\"Lawyer to Sue Employer for Hostile Work Environment\\u00a0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/#listItem\",\"position\":3,\"name\":\"Lawyer to Sue Employer for Hostile Work Environment\\u00a0\",\"item\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/#listItem\",\"name\":\"Attorney to Sue Employer for Hostile Work Environment\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/#listItem\",\"name\":\"Practice Areas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/#listItem\",\"position\":4,\"name\":\"Attorney to Sue Employer for Hostile Work Environment\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/#listItem\",\"name\":\"Lawyer to Sue Employer for Hostile Work Environment\\u00a0\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/#organization\",\"name\":\"California Labor Law Employment Attorneys Group\",\"url\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/\",\"email\":\"info@losangelesemploymentattorney.org\",\"telephone\":\"+18884518915\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"value\":400},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/clleaglogoss-01.png\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/#organizationLogo\",\"width\":854,\"height\":261},\"image\":{\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/#organizationLogo\"},\"address\":{\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"612 S Broadway, Suite 600\",\"postalCode\":\"90014\",\"addressLocality\":\"Los Angeles\",\"addressRegion\":\"California\",\"addressCountry\":\"US\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/#webpage\",\"url\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/\",\"name\":\"Attorney to Sue Employer for Hostile Work Environment - California Labor Law Employment Attorneys Group\",\"description\":\"Every employee is entitled to a safe and accepting workplace. There have been many laws implemented to make sure that peace is kept at job environments, both internally and externally. There have also been laws passed that prevent discrimination from taking place at a job \\u2013 this means that, as a prospective employee, you cannot\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/practice-areas\\\/workplace-hostility-harassment\\\/hostile-work-environment-harassment-lawyer\\\/#breadcrumblist\"},\"datePublished\":\"2017-12-14T01:18:31+00:00\",\"dateModified\":\"2025-12-11T22:18:44+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/\",\"name\":\"California Labor Law Employment Attorneys Group\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.losangelesemploymentattorney.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Attorney to Sue Employer for Hostile Work Environment - California Labor Law Employment Attorneys Group<\/title>\n\n","aioseo_head_json":{"title":"Abogado demandar\u00e1 al empleador por ambiente laboral hostil - Grupo de abogados de empleo en derecho laboral de California","description":"Todo empleado tiene derecho a un lugar de trabajo seguro y acogedor. Se han implementado muchas leyes para garantizar que se mantenga la paz en el entorno laboral, tanto interna como externamente. Tambi\u00e9n se han aprobado leyes que impiden que se produzca discriminaci\u00f3n en el trabajo; esto significa que, como posible empleado, no puedes","canonical_url":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es#listItem","position":1,"name":"Home","item":"https:\/\/www.losangelesemploymentattorney.org\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/#listItem","name":"Practice Areas"}},{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/#listItem","position":2,"name":"Practice Areas","item":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/#listItem","name":"Lawyer to Sue Employer for Hostile Work Environment\u00a0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/#listItem","position":3,"name":"Lawyer to Sue Employer for Hostile Work Environment\u00a0","item":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/#listItem","name":"Attorney to Sue Employer for Hostile Work Environment"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/#listItem","name":"Practice Areas"}},{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/#listItem","position":4,"name":"Attorney to Sue Employer for Hostile Work Environment","previousItem":{"@type":"ListItem","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/#listItem","name":"Lawyer to Sue Employer for Hostile Work Environment\u00a0"}}]},{"@type":"Organization","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/#organization","name":"California Labor Law Employment Attorneys Group","url":"https:\/\/www.losangelesemploymentattorney.org\/es\/","email":"info@losangelesemploymentattorney.org","telephone":"+18884518915","numberOfEmployees":{"@type":"QuantitativeValue","value":400},"logo":{"@type":"ImageObject","url":"https:\/\/www.losangelesemploymentattorney.org\/wp-content\/uploads\/2021\/12\/clleaglogoss-01.png","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/#organizationLogo","width":854,"height":261},"image":{"@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/#organizationLogo"},"address":{"@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/#postaladdress","@type":"PostalAddress","streetAddress":"612 S Broadway, Suite 600","postalCode":"90014","addressLocality":"Los Angeles","addressRegion":"California","addressCountry":"US"}},{"@type":"WebPage","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/#webpage","url":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/","name":"Attorney to Sue Employer for Hostile Work Environment - California Labor Law Employment Attorneys Group","description":"Every employee is entitled to a safe and accepting workplace. There have been many laws implemented to make sure that peace is kept at job environments, both internally and externally. There have also been laws passed that prevent discrimination from taking place at a job \u2013 this means that, as a prospective employee, you cannot","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/#breadcrumblist"},"datePublished":"2017-12-14T01:18:31+00:00","dateModified":"2025-12-11T22:18:44+00:00"},{"@type":"WebSite","@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/#website","url":"https:\/\/www.losangelesemploymentattorney.org\/es\/","name":"California Labor Law Employment Attorneys Group","inLanguage":"es-MX","publisher":{"@id":"https:\/\/www.losangelesemploymentattorney.org\/es\/#organization"}}]},"og:locale":"es_MX","og:site_name":"California Labor Law Employment Attorneys Group -","og:type":"article","og:title":"Attorney to Sue Employer for Hostile Work Environment - California Labor Law Employment Attorneys Group","og:description":"Every employee is entitled to a safe and accepting workplace. There have been many laws implemented to make sure that peace is kept at job environments, both internally and externally. There have also been laws passed that prevent discrimination from taking place at a job \u2013 this means that, as a prospective employee, you cannot","og:url":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/","article:published_time":"2017-12-14T01:18:31+00:00","article:modified_time":"2025-12-11T22:18:44+00:00","twitter:card":"summary_large_image","twitter:title":"Attorney to Sue Employer for Hostile Work Environment - California Labor Law Employment Attorneys Group","twitter:description":"Every employee is entitled to a safe and accepting workplace. There have been many laws implemented to make sure that peace is kept at job environments, both internally and externally. There have also been laws passed that prevent discrimination from taking place at a job \u2013 this means that, as a prospective employee, you cannot"},"aioseo_meta_data":{"post_id":"1310","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-06-09 23:36:16","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-01-10 00:10:31","updated":"2026-06-09 23:36:16","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.losangelesemploymentattorney.org\/es\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/\" title=\"Practice Areas\">Practice Areas<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/\" title=\"Lawyer to Sue Employer for Hostile Work Environment \">Lawyer to Sue Employer for Hostile Work Environment <\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAttorney to Sue Employer for Hostile Work Environment\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.losangelesemploymentattorney.org\/es"},{"label":"Practice Areas","link":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/"},{"label":"Lawyer to Sue Employer for Hostile Work Environment\u00a0","link":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/"},{"label":"Attorney to Sue Employer for Hostile Work Environment","link":"https:\/\/www.losangelesemploymentattorney.org\/es\/practice-areas\/workplace-hostility-harassment\/hostile-work-environment-harassment-lawyer\/"}],"_links":{"self":[{"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/pages\/1310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/comments?post=1310"}],"version-history":[{"count":8,"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/pages\/1310\/revisions"}],"predecessor-version":[{"id":13986,"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/pages\/1310\/revisions\/13986"}],"up":[{"embeddable":true,"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/pages\/1430"}],"wp:attachment":[{"href":"https:\/\/www.losangelesemploymentattorney.org\/es\/wp-json\/wp\/v2\/media?parent=1310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}